{"id":144820,"date":"2024-09-16T11:32:20","date_gmt":"2024-09-16T09:32:20","guid":{"rendered":"https:\/\/www.metrica.it\/prodotto\/medidor-de-espesor-de-cuadrante-decimal\/"},"modified":"2024-09-16T20:25:12","modified_gmt":"2024-09-16T18:25:12","slug":"medidor-de-espesor-de-cuadrante-decimal","status":"publish","type":"product","link":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/","title":{"rendered":"Medidor De Espesor De Cuadrante Decimal"},"content":{"rendered":"<ul>\n<li>Lectura de 0,1 mm<\/li>\n<li>Mango ergon\u00f3mico<\/li>\n<li>Soporte en aluminio y pintura anti rasgu\u00f1o<\/li>\n<li>Palanca elevadora<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Lectura de 0,1 mm<br \/>Mango ergon\u00f3mico<br \/>Soporte en aluminio y pintura anti rasgu\u00f1o<br \/>Palanca elevadora<\/p>\n","protected":false},"featured_media":124521,"template":"","meta":[],"product_cat":[643,667],"product_tag":[],"class_list":{"0":"post-144820","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mediciones-mecanicas","7":"product_cat-medidores-de-dureza-de-espesura-plicometros","9":"first","10":"instock","11":"sold-individually","12":"product-type-simple"},"yoast_head":"<title>Misuratore Di Spessore A Quadrante Decimale | Medidores de Dureza, de espesura - plic\u00f3metros | Mediciones Mec\u00e1nicas - Metrica<\/title>\n<meta name=\"description\" content=\"Descubre la colecci\u00f3n de productos., Misuratore Di Spessore A Quadrante Decimale - Medidores de Dureza, de espesura - plic\u00f3metros. Lettura 0,1 mm Impugnatura ergonomica Supporto in alluminio e ver . Consulta el cat\u00e1logo en la web oficial de Metrica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Misuratore Di Spessore A Quadrante Decimale | Medidores de Dureza, de espesura - plic\u00f3metros | Mediciones Mec\u00e1nicas - Metrica\" \/>\n<meta property=\"og:description\" content=\"Descubre la colecci\u00f3n de productos., Misuratore Di Spessore A Quadrante Decimale - Medidores de Dureza, de espesura - plic\u00f3metros. Lettura 0,1 mm Impugnatura ergonomica Supporto in alluminio e ver . Consulta el cat\u00e1logo en la web oficial de Metrica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/\" \/>\n<meta property=\"og:site_name\" content=\"Metrica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T18:25:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/producto\\\/medidor-de-espesor-de-cuadrante-decimal\\\/\",\"url\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/producto\\\/medidor-de-espesor-de-cuadrante-decimal\\\/\",\"name\":\"Misuratore Di Spessore A Quadrante Decimale | Medidores de Dureza, de espesura - plic\u00f3metros | Mediciones Mec\u00e1nicas - Metrica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/producto\\\/medidor-de-espesor-de-cuadrante-decimal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/producto\\\/medidor-de-espesor-de-cuadrante-decimal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metrica.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/43055_1.jpg\",\"datePublished\":\"2024-09-16T09:32:20+00:00\",\"dateModified\":\"2024-09-16T18:25:12+00:00\",\"description\":\"Descubre la colecci\u00f3n de productos., Misuratore Di Spessore A Quadrante Decimale - Medidores de Dureza, de espesura - plic\u00f3metros. Lettura 0,1 mm Impugnatura ergonomica Supporto in alluminio e ver . Consulta el cat\u00e1logo en la web oficial de Metrica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/producto\\\/medidor-de-espesor-de-cuadrante-decimal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metrica.it\\\/es\\\/producto\\\/medidor-de-espesor-de-cuadrante-decimal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/producto\\\/medidor-de-espesor-de-cuadrante-decimal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.metrica.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/43055_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.metrica.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/43055_1.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/producto\\\/medidor-de-espesor-de-cuadrante-decimal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo\",\"item\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/catalogo-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Medidor De Espesor De Cuadrante Decimal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/\",\"name\":\"Metrica\",\"description\":\"Made to measure\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metrica.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>","yoast_head_json":{"title":"Misuratore Di Spessore A Quadrante Decimale | Medidores de Dureza, de espesura - plic\u00f3metros | Mediciones Mec\u00e1nicas - Metrica","description":"Descubre la colecci\u00f3n de productos., Misuratore Di Spessore A Quadrante Decimale - Medidores de Dureza, de espesura - plic\u00f3metros. Lettura 0,1 mm Impugnatura ergonomica Supporto in alluminio e ver . Consulta el cat\u00e1logo en la web oficial de Metrica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/","og_locale":"es_ES","og_type":"article","og_title":"Misuratore Di Spessore A Quadrante Decimale | Medidores de Dureza, de espesura - plic\u00f3metros | Mediciones Mec\u00e1nicas - Metrica","og_description":"Descubre la colecci\u00f3n de productos., Misuratore Di Spessore A Quadrante Decimale - Medidores de Dureza, de espesura - plic\u00f3metros. Lettura 0,1 mm Impugnatura ergonomica Supporto in alluminio e ver . Consulta el cat\u00e1logo en la web oficial de Metrica.","og_url":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/","og_site_name":"Metrica","article_modified_time":"2024-09-16T18:25:12+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/","url":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/","name":"Misuratore Di Spessore A Quadrante Decimale | Medidores de Dureza, de espesura - plic\u00f3metros | Mediciones Mec\u00e1nicas - Metrica","isPartOf":{"@id":"https:\/\/www.metrica.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/#primaryimage"},"image":{"@id":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055_1.jpg","datePublished":"2024-09-16T09:32:20+00:00","dateModified":"2024-09-16T18:25:12+00:00","description":"Descubre la colecci\u00f3n de productos., Misuratore Di Spessore A Quadrante Decimale - Medidores de Dureza, de espesura - plic\u00f3metros. Lettura 0,1 mm Impugnatura ergonomica Supporto in alluminio e ver . Consulta el cat\u00e1logo en la web oficial de Metrica.","breadcrumb":{"@id":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/#primaryimage","url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055_1.jpg","contentUrl":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055_1.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.metrica.it\/es\/producto\/medidor-de-espesor-de-cuadrante-decimal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.metrica.it\/es\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo","item":"https:\/\/www.metrica.it\/es\/catalogo-es\/"},{"@type":"ListItem","position":3,"name":"Medidor De Espesor De Cuadrante Decimal"}]},{"@type":"WebSite","@id":"https:\/\/www.metrica.it\/es\/#website","url":"https:\/\/www.metrica.it\/es\/","name":"Metrica","description":"Made to measure","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metrica.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"meta_box":{"awr_documentation":[],"awr_manuale":[],"awr_scheda_tecnica":"","awr_youtube_video":"","awr_classe_prodotto":"","awr_customize_product":"1","awr_custom_image":{"width":96,"height":96,"file":"2024\/05\/43055.jpg","filesize":463285,"sizes":{"dgwt-wcas-product-suggestion":{"file":"43055-64x64.jpg","width":64,"height":64,"mime-type":"image\/jpeg","filesize":2014,"url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-64x64.jpg"},"hongo-product-icon-image":{"file":"43055-64x64.jpg","width":64,"height":64,"mime-type":"image\/jpeg","filesize":2014,"url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-64x64.jpg"},"hongo-product-small-image":{"file":"43055-84x84.jpg","width":84,"height":84,"mime-type":"image\/jpeg","filesize":2704,"url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-84x84.jpg"},"hongo-medium-image":{"file":"43055-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":27357,"url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-450x450.jpg"},"post-thumbnail":{"file":"43055-790x790.jpg","width":790,"height":790,"mime-type":"image\/jpeg","filesize":66345,"url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-790x790.jpg"},"hongo-shop-image":{"file":"43055-660x660.jpg","width":660,"height":660,"mime-type":"image\/jpeg","filesize":50377,"url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-660x660.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]},"ID":"124516","name":"43055.jpg","path":"\/var\/www\/html\/wp-content\/uploads\/2024\/05\/43055.jpg","url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055.jpg","full_url":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055.jpg","title":"43055.jpg","caption":"","description":"","alt":"","srcset":"https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055.jpg 800w, https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-64x64.jpg 64w, https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-84x84.jpg 84w, https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-450x450.jpg 450w, https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-790x790.jpg 790w, https:\/\/www.metrica.it\/wp-content\/uploads\/2024\/05\/43055-660x660.jpg 660w"},"awr_related_products":[{"awr_product_name":"Misuratore Di Spessore A Quadrante Decimale","awr_product_references":"ref:43049|ean:8001066430499|c_mm:0 - 30|p_mm:200|unit_misura_mm:0.1|contatto:k|pack:1"},{"awr_product_name":"Misuratore Di Spessore A Quadrante Decimale","awr_product_references":"ref:43055|ean:8001066430550|c_mm:0 - 30|p_mm:200|unit_misura_mm:0.1|contatto:f|pack:1"},{"awr_product_name":"Misuratore Di Spessore A Quadrante Decimale","awr_product_references":"ref:43056|ean:8001066430567|c_mm:0 - 30|p_mm:300|unit_misura_mm:0.1|contatto:f|pack:1"},{"awr_product_name":"Misuratore Di Spessore A Quadrante Decimale","awr_product_references":"ref:43057|ean:8001066430574|c_mm:0 - 30|p_mm:450|unit_misura_mm:0.1|contatto:f|pack:1"},{"awr_product_name":"Misuratore Di Spessore A Quadrante Decimale","awr_product_references":"ref:43059|ean:8001066430598|c_mm:0 - 50|p_mm:300|unit_misura_mm:0.1|contatto:f|pack:1"},{"awr_product_name":"Misuratore Di Spessore A Quadrante Decimale","awr_product_references":"ref:43060|ean:8001066430604|c_mm:0 - 50|p_mm:500|unit_misura_mm:0.1|contatto:f|pack:1"},{"awr_product_name":"Misuratore Di Spessore A Quadrante Decimale","awr_product_references":"ref:43061|ean:8001066430611|c_mm:0 - 30|p_mm:300|unit_misura_mm:0.1|contatto:k|pack:1"}],"awr_consumabili":"","awr_alternativi":"","awr_aliases":"43049,43055,43056,43057,43059,43060,43061","awr_skuid":"43055-it"},"_links":{"self":[{"href":"https:\/\/www.metrica.it\/es\/wp-json\/wp\/v2\/product\/144820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metrica.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.metrica.it\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metrica.it\/es\/wp-json\/wp\/v2\/media\/124521"}],"wp:attachment":[{"href":"https:\/\/www.metrica.it\/es\/wp-json\/wp\/v2\/media?parent=144820"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.metrica.it\/es\/wp-json\/wp\/v2\/product_cat?post=144820"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.metrica.it\/es\/wp-json\/wp\/v2\/product_tag?post=144820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}